{"id":201,"date":"2016-12-16T13:47:51","date_gmt":"2016-12-16T13:47:51","guid":{"rendered":"http:\/\/gableinsurance.li\/?page_id=201"},"modified":"2021-11-10T11:16:47","modified_gmt":"2021-11-10T11:16:47","slug":"register-for-newsletter","status":"publish","type":"page","link":"https:\/\/gableinsurance.li\/it\/register-for-newsletter\/","title":{"rendered":"Registrare per newsletter"},"content":{"rendered":"\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f650-o1\" lang=\"de-CH\" dir=\"ltr\" data-wpcf7-id=\"650\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/201#wpcf7-f650-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"650\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_CH\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f650-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Titolo (richiesto)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"title\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"title\"><option value=\"\">&#8211; Bitte ausw\u00e4hlen &#8211;<\/option><option value=\"Signora\">Signora<\/option><option value=\"Signor\">Signor<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> Nome (richiesto)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Cognome (richiesto)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email (richiesto)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Paese (richiesto) <span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"country\" \/><\/span><\/label>\n<\/p>\n<p><label> Nome del broker<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"broker-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"broker-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Numero di telefono (con prefisso internazionale)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"phone\" \/><\/span> <\/label>\n<\/p>\n<p><label> Data di nascita <span class=\"wpcf7-form-control-wrap\" data-name=\"placeholder\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"YYYY\/MM\/DD\" type=\"text\" name=\"placeholder\" \/><\/span> <\/label>\n<\/p>\n<p><label>Numero polizza (richiesto)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"policy-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"policy-number\" \/><\/span> <\/label>\n<\/p>\n<p><span id=\"wpcf7-6a58066036097-wrapper\" class=\"wpcf7-form-control-wrap e-mail-507-wrap\" style=\"display:none !important; visibility:hidden !important;\"><input type=\"hidden\" name=\"e-mail-507-time-start\" value=\"1784153696\"><input type=\"hidden\" name=\"e-mail-507-time-check\" value=\"4\"><label for=\"wpcf7-6a58066036097-field\" class=\"hp-message\">Bitte lassen Sie dieses Feld leer.<\/label><input id=\"wpcf7-6a58066036097-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"e-mail-507\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner gable-form-submit\" type=\"submit\" value=\"Registrare\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-201","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"it","enabled_languages":["de","en","it","fr"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/pages\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":14,"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/pages\/201\/revisions"}],"predecessor-version":[{"id":1212,"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/pages\/201\/revisions\/1212"}],"wp:attachment":[{"href":"https:\/\/gableinsurance.li\/it\/wp-json\/wp\/v2\/media?parent=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}